{"id":3712,"date":"2020-03-09T12:11:09","date_gmt":"2020-03-09T11:11:09","guid":{"rendered":"https:\/\/comanai.com\/?page_id=3712"},"modified":"2020-05-07T18:29:24","modified_gmt":"2020-05-07T16:29:24","slug":"comanai-steam","status":"publish","type":"page","link":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/","title":{"rendered":"COMANAI-STEAM"},"content":{"rendered":"<div id='layer_slider_1'  class='avia-layerslider main_color avia-shadow  avia-builder-el-0  el_before_av_section  avia-builder-el-first  container_wrap sidebar_right'  style='height: 651px;'  ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-362xx9-4f71204e8908f4aec68f9cbef53298b1\">\n.avia-section.av-362xx9-4f71204e8908f4aec68f9cbef53298b1{\nbackground-color:#f7f7f7;\n}\n.avia-section.av-362xx9-4f71204e8908f4aec68f9cbef53298b1 .av-section-color-overlay{\nopacity:0.5;\nbackground-image:url(https:\/\/comanai.com\/wp-content\/themes\/enfold\/images\/background-images\/noise-for-light-background.png);\nbackground-repeat:repeat;\n}\n.avia-section.av-362xx9-4f71204e8908f4aec68f9cbef53298b1 .av-extra-border-element .av-extra-border-inner{\nbackground-color:#f7f7f7;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-362xx9-4f71204e8908f4aec68f9cbef53298b1 main_color avia-section-small avia-shadow  avia-builder-el-1  el_after_av_layerslider  el_before_av_section  avia-bg-style-scroll av-section-color-overlay-active av-arrow-down-section container_wrap sidebar_right'  ><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3712'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3zkbyo-5706c5d9165184a4c09fcdc8ee196b4e\">\n.flex_column.av-3zkbyo-5706c5d9165184a4c09fcdc8ee196b4e{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3zkbyo-5706c5d9165184a4c09fcdc8ee196b4e av_one_half  avia-builder-el-2  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-k7bvaosd-e08b8eb6e8240ab346763fff14fe7557 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>En <strong>COMANAI SMARTER ENGINEERING <\/strong>promovemos el pensamiento cient\u00edfico, el conocimiento tecnol\u00f3gico y la innovaci\u00f3n en la <strong>Educaci\u00f3n<\/strong>. Para ello creamos <strong>COMANAI STEAM<\/strong>.<\/p>\n<p>El futuro de nuestras ni\u00f1as y ni\u00f1os, y la <strong>igualdad de oportunidades<\/strong>\u00a0en un mundo en el que la tecnolog\u00eda nos envuelve y es cada vez m\u00e1s compleja, pasa por una <strong>formaci\u00f3n dirigida a la resoluci\u00f3n de problemas complejos.<\/strong><\/p>\n<p>Formaci\u00f3n para construir <strong>soluciones creativas e innovadoras<\/strong> aprovechando las tecnolog\u00edas disponibles para desarrollar procesos que tengan sentido para las comunidades educativas.<\/p>\n<p>Una Educaci\u00f3n sobre las dimensiones de equidad, pertinencia, relevancia, eficiencia y eficacia para el desarrollo integral e interdisciplinar de:<\/p>\n<ul>\n<li>Habilidades fundamentales (lectoescritura, \u00e1lgebra, ciencias, inform\u00e1tica, artes, cultura c\u00edvica y financiera).<\/li>\n<li>Competencias relacionadas con dichas habilidades (pensamiento cr\u00edtico, creatividad, comunicaci\u00f3n y colaboraci\u00f3n) para abordar desaf\u00edos complejos.<\/li>\n<li>Y, por \u00faltimo, los cambios que nos esperan requieren cualidades de car\u00e1cter (curiosidad, iniciativa, persistencia, adaptabilidad, liderazgo, y sensibilidad social y cultural).<\/li>\n<\/ul>\n<p>Ese es el punto de partida del concepto educativo <strong>STEAM<\/strong> (Science, Technology, Engineering Arts and Mathematics), respuesta estructural al desaf\u00edo que supone un presente de cambio tecnol\u00f3gico constante y un <strong>futuro inmediato de empleos hoy inexistentes<\/strong>.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-375yeo-37f0c20debdba8c3b00045bd1768cd38\">\n.flex_column.av-375yeo-37f0c20debdba8c3b00045bd1768cd38{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-375yeo-37f0c20debdba8c3b00045bd1768cd38 av_one_half  avia-builder-el-4  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7kdrbsc-da5d534028e42ef45d2a04d727e888d3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ITJUQre19Mg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Future jobs and industry: responding to the speed of change\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ITJUQre19Mg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><div class='av-extra-border-element border-extra-arrow-down'><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2b5orh-00ad616e8fe5b23f3d6a8bf0ff9c3329\">\n.avia-section.av-2b5orh-00ad616e8fe5b23f3d6a8bf0ff9c3329{\nbackground-color:#ffffff;\nbackground-image:unset;\n}\n.avia-section.av-2b5orh-00ad616e8fe5b23f3d6a8bf0ff9c3329 .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-2b5orh-00ad616e8fe5b23f3d6a8bf0ff9c3329 main_color avia-section-large avia-no-shadow  avia-builder-el-6  el_after_av_section  el_before_av_section  avia-bg-style-scroll av-arrow-down-section container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3712'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3pfqyo-1f026d1da2ebbf30babb54f968067cb7\">\n.flex_column.av-3pfqyo-1f026d1da2ebbf30babb54f968067cb7{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3pfqyo-1f026d1da2ebbf30babb54f968067cb7 av_one_fourth  avia-builder-el-7  el_before_av_three_fourth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-k7bvaosd-e08b8eb6e8240ab346763fff14fe7557 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><span style=\"color: #e77000;\"><strong>S<\/strong><\/span>cience<\/h2>\n<h2><span style=\"color: #e77000;\"><strong>T<\/strong><\/span>echnology<\/h2>\n<h2><span style=\"color: #e77000;\"><strong>E<\/strong><\/span>ngineering<\/h2>\n<h2><span style=\"color: #e77000;\"><strong>A<\/strong><\/span>rts<\/h2>\n<h2><span style=\"color: #e77000;\"><strong>M<\/strong><\/span>athematics<\/h2>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1w4a6o-6433e3d4ddc8b3a5f8a0cc6495498942\">\n.flex_column.av-1w4a6o-6433e3d4ddc8b3a5f8a0cc6495498942{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1w4a6o-6433e3d4ddc8b3a5f8a0cc6495498942 av_three_fourth  avia-builder-el-9  el_after_av_one_fourth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-k7bvaosd-e08b8eb6e8240ab346763fff14fe7557 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>El 65% del alumnado que hoy ingresa en las escuelas primarias trabajar\u00e1 en empleos que hoy no existen, seg\u00fan estimaci\u00f3n del <strong>Foro Econ\u00f3mico Mundial.<\/strong> La <strong>UNESCO<\/strong> advierte que el desarrollo econ\u00f3mico y social necesita del progreso de la ciencia y la tecnolog\u00eda y de su implantaci\u00f3n en todos los niveles educativos.<\/p>\n<p>De hecho, Espa\u00f1a tiene un amplio margen de mejora para acercarse a los l\u00edderes en econom\u00eda y sociedad digital, en especial a lo referente a la <strong>formaci\u00f3n en el uso de nuevas tecnolog\u00edas<\/strong>, como refleja el <a href=\"https:\/\/circulodeempresarios.org\/transformacion-digital\/wp-content\/uploads\/2018\/05\/es-desi_2018-country-profile_eng.pdf\"><span style=\"text-decoration: underline; color: #e77000;\"><strong>indicador DESI\u00a0(Digital Economy and Society Index) de la Comisi\u00f3n Europea<\/strong><\/span><\/a>.<\/p>\n<p>A ello se suma que la frontera tecnol\u00f3gica sigue desplaz\u00e1ndose a gran velocidad, la disponibilidad de datos es cada vez mayor, el avance de la inteligencia artificial\u2026 Avances que se aplican en \u00e1mbitos de nuestra vida que hace solo unos a\u00f1os nunca hubi\u00e9ramos imaginado.<\/p>\n<\/div><\/section><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><div class='av-extra-border-element border-extra-arrow-down'><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-362xx9-89375bd36a52c53052108de2b5d8ec2d\">\n.avia-section.av-362xx9-89375bd36a52c53052108de2b5d8ec2d{\nbackground-color:#e77000;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-362xx9-89375bd36a52c53052108de2b5d8ec2d main_color avia-section-default avia-no-border-styling  avia-builder-el-11  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3712'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7bvaosd-85503546353c1f6cffa20bd6d1ed239b\">\n#top .av_textblock_section.av-k7bvaosd-85503546353c1f6cffa20bd6d1ed239b .avia_textblock{\nfont-size:24px;\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-k7bvaosd-85503546353c1f6cffa20bd6d1ed239b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><blockquote>\n<p style=\"text-align: center;\"><strong><em>\u00bfPor qu\u00e9 es tan importante STEAM para COMANAI?<\/em><\/strong><\/p>\n<\/blockquote>\n<\/div><\/section>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-362xx9-b9bcb75f3a33b8fd944a652935d16392\">\n.avia-section.av-362xx9-b9bcb75f3a33b8fd944a652935d16392{\nbackground-color:#f7f7f7;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_4'  class='avia-section av-362xx9-b9bcb75f3a33b8fd944a652935d16392 main_color avia-section-default avia-no-border-styling  avia-builder-el-13  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3712'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-k7bvaosd-e08b8eb6e8240ab346763fff14fe7557 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Porque promueve una cultura de <strong>pensamiento cient\u00edfico<\/strong> para la toma de decisiones lo que resulta muy \u00fatil tanto dentro como sobretodo fuera del aula.<\/li>\n<li>Porque permite la adquisici\u00f3n de <strong>conocimientos tecnol\u00f3gicos y cient\u00edficos<\/strong>, aplicables a cualquier posible situaci\u00f3n que pueda aparecer en el futuro desde una perspectiva integrada.<\/li>\n<li>Porque esta integraci\u00f3n del conocimiento permite una mayor <strong>conciencia de las relaciones entre las diferentes \u00e1reas del saber<\/strong>, asegurando un mayor grado de participaci\u00f3n activa.<\/li>\n<li>Porque gracias al factor creativo, la \u2018A\u2019 de STEAM, el alumnado no solo puede desarrollar las competencias para la resoluci\u00f3n de problemas, o el an\u00e1lisis, sino tambi\u00e9n<strong> la innovaci\u00f3n y el pensamiento creativo y cr\u00edtico<\/strong>.<\/li>\n<\/ul>\n<p><strong>COMANAI-STEAM<\/strong> se est\u00e1 transformando en un espacio de <strong>aprendizaje compartido <\/strong>con algunos de nuestros mejores colaboradores y clientes. A todos ellos les agradecemos que hayan hecho suyo el compromiso de <strong>COMANAI SMARTER ENGINEERING <\/strong>con el futuro de nuestras ni\u00f1as y ni\u00f1os.<\/p>\n<\/div><\/section>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-362xx9-b9bcb75f3a33b8fd944a652935d16392\">\n.avia-section.av-362xx9-b9bcb75f3a33b8fd944a652935d16392{\nbackground-color:#f7f7f7;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-362xx9-b9bcb75f3a33b8fd944a652935d16392 main_color avia-section-default avia-no-border-styling  avia-builder-el-15  el_after_av_section  el_before_av_layout_row  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-3712'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-video av-k7kdrbsc-d3d58503eea2fea0781cdaedabb4210b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/P3Bv5wjMJO8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"AURRERAPENA: \ud83c\udff3\ufe0f\u200d\ud83c\udf08ASKE!!\ud83c\udff3\ufe0f\u200d\ud83c\udf08 JASO MUSIKALA\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/P3Bv5wjMJO8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-k7bvaosd-e08b8eb6e8240ab346763fff14fe7557 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2><span style=\"font-weight: 400;\">Como patrocinador principal de la Fundaci\u00f3n Ikastola Jaso, COMANAI contribuye, a trav\u00e9s de <\/span><b>COMANAI-STEAM<\/b><span style=\"font-weight: 400;\"> a la innovaci\u00f3n y desarrollo econ\u00f3mico y social a trav\u00e9s del proyecto <em><strong>Jaso Musikala<\/strong><\/em>.<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En <em><strong>Jaso Musikala<\/strong><\/em> j\u00f3venes entre 12 y 16 a\u00f1os descubren y adquieren conocimientos y habilidades significativas sobre ciencia, tecnolog\u00eda, ingenier\u00eda, artes y matem\u00e1ticas (STEAM) y desarrollan en equipo procesos y soluciones de ingenier\u00eda para su aplicaci\u00f3n en la <\/span><b>puesta en escena de un espect\u00e1culo musical que a\u00fana canto, baile, acrobacias, m\u00fasica en directo y efectos especiales<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una de las claves de la Educaci\u00f3n STEAM son los espacios <\/span><i><span style=\"font-weight: 400;\">maker<\/span><\/i><span style=\"font-weight: 400;\">, para crear. \u00abAprender haciendo\u201d. <\/span><span style=\"font-weight: 400;\">As\u00ed, en el proyecto art\u00edstico de <strong><em>Jaso Musikala<\/em><\/strong> el alumnado trabaja conceptos de Matem\u00e1tica, F\u00edsica, Qu\u00edmica\u2026 cuando, entre otras tareas:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Dise\u00f1a la escenograf\u00eda<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Dise\u00f1a la iluminaci\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Conoce el funcionamiento y aprende a trabajar con sistemas de iluminaci\u00f3n LED<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Colabora en la programaci\u00f3n de la sonorizaci\u00f3n del espect\u00e1culo<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Aprende las claves para el funcionamiento de un AGV (<\/span><span style=\"font-weight: 400;\">Automatic Guided Vehicle)&#8230;<\/span><\/li>\n<\/ul>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-vq9ow-6766ac8579149e71fef1fa933030bd94\">\n.flex_column.av-vq9ow-6766ac8579149e71fef1fa933030bd94{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-vq9ow-6766ac8579149e71fef1fa933030bd94 av_one_fifth  avia-builder-el-18  el_after_av_textblock  el_before_av_one_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-k86bdgz0-3476bce23b0cb5f2035d5b3d5d3d6b14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><strong>S<\/strong><\/h2>\n<h3 style=\"text-align: center;\"><strong>S<\/strong>cience<\/h3>\n<ul>\n<li>Ejemplo de hielo seco: reacciones qu\u00edmicas.<\/li>\n<li>Ejercicios f\u00edsicos con c\u00e1lculos de acrobacia.<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7qpqa8-a7f42f776409341a5a7ee97127229f9d\">\n.flex_column.av-7qpqa8-a7f42f776409341a5a7ee97127229f9d{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-7qpqa8-a7f42f776409341a5a7ee97127229f9d av_one_fifth  avia-builder-el-20  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-k86bdgz0-3476bce23b0cb5f2035d5b3d5d3d6b14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><strong>T<\/strong><\/h2>\n<h3 style=\"text-align: center;\"><strong>T<\/strong>echnology<\/h3>\n<ul>\n<li>Creaci\u00f3n de escenograf\u00eda, medidas, corte, materiales.<\/li>\n<li>Conceptos de electricidad.<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6awdi8-a52b217ff155b793274a11fdc9f61f53\">\n.flex_column.av-6awdi8-a52b217ff155b793274a11fdc9f61f53{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-6awdi8-a52b217ff155b793274a11fdc9f61f53 av_one_fifth  avia-builder-el-22  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-k86bdgz0-3476bce23b0cb5f2035d5b3d5d3d6b14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><strong>E<\/strong><\/h2>\n<h3 style=\"text-align: center;\"><strong>E<\/strong>ngineering<\/h3>\n<ul>\n<li>Pensar como hacer el atrezzo.<\/li>\n<li>Programaci\u00f3n y dise\u00f1o de luces.<\/li>\n<li>Dise\u00f1o y programaci\u00f3n de sonido.<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3rgu4w-d56b9e743c521be0c01f6c30030a5cfa\">\n.flex_column.av-3rgu4w-d56b9e743c521be0c01f6c30030a5cfa{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3rgu4w-d56b9e743c521be0c01f6c30030a5cfa av_one_fifth  avia-builder-el-24  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-k86bdgz0-3476bce23b0cb5f2035d5b3d5d3d6b14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><strong>A<\/strong><\/h2>\n<h3 style=\"text-align: center;\"><strong>A<\/strong>rt<\/h3>\n<ul>\n<li>Canto<\/li>\n<li>Danza<\/li>\n<li>Coreograf\u00edas<\/li>\n<li>Dise\u00f1o de vestuario<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1uwk40-070bb938f1c614cae1123242c1f6a4ec\">\n.flex_column.av-1uwk40-070bb938f1c614cae1123242c1f6a4ec{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1uwk40-070bb938f1c614cae1123242c1f6a4ec av_one_fifth  avia-builder-el-26  el_after_av_one_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-k86bdgz0-3476bce23b0cb5f2035d5b3d5d3d6b14 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h2 style=\"text-align: center;\"><strong>M<\/strong><\/h2>\n<h3 style=\"text-align: center;\"><strong>M<\/strong>athematics<\/h3>\n<ul>\n<li>C\u00e1lculos para memorias de sonido y luces.<\/li>\n<li>Calcular tama\u00f1os de escenograf\u00eda, contrapesos, poleas, etc.<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-6eoh74-1d12842f9bd2adc049f5bd9cb5ea15ea entry-content-wrapper main_color av-border-top-bottom av-fixed-cells  avia-builder-el-28  el_after_av_section  avia-builder-el-last  grid-row-not-first  container_wrap sidebar_right'  >\n<div class='flex_cell av-3w4g34-6ba3f754ca5a056d61b7b422789f4754 av-gridrow-cell av_one_fifth no_margin  avia-builder-el-29  el_before_av_cell_three_fifth  avia-builder-el-first ' ><div class='flex_cell_inner'><\/div><\/div><div class='flex_cell av-2x88bk-b78434454d321cf185fd90b2c577b4a1 av-gridrow-cell av_three_fifth no_margin  avia-builder-el-30  el_after_av_cell_one_fifth  el_before_av_cell_one_fifth ' ><div class='flex_cell_inner'><section  class='av_textblock_section av-29v6jk-63e739f2765894f023a82cc5401370e0 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: left;\"><strong>\u00bfQuieres conocer m\u00e1s sobre nuestro proyecto?<\/strong> Cont\u00e1ctanos y te explicaremos m\u00e1s sobre COMANAI STEAM y nuestros proyectos de futuro.<\/p>\n<\/div><\/section><br \/>\n<form action=\"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/\" method=\"post\" data-fields-with-error=\"Found errors in the following field(s):\" class=\"avia_ajax_form av-form-labels-visible   avia-builder-el-32  el_after_av_textblock  avia-builder-el-last   \" data-avia-form-id=\"1\" data-avia-redirect='' ><fieldset><p class='  first_form  form_element form_fullwidth' id='element_avia_1_1'><label for=\"avia_1_1\">Nombre <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label> <input name=\"avia_1_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_1_1\" value=\"\" \/><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_2_1'><label for=\"avia_2_1\">Correo electr\u00f3nico <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label> <input name=\"avia_2_1\" class=\"text_input is_email\" type=\"text\" id=\"avia_2_1\" value=\"\" \/><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_3_1'><label for=\"avia_3_1\">Asunto <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label> <input name=\"avia_3_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_3_1\" value=\"\" \/><\/p><p class='  first_form  form_element form_fullwidth' id='element_avia_4_1'><label for=\"avia_4_1\" class=\"textare_label hidden textare_label_avia_4_1\">Mensaje <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label><textarea  name=\"avia_4_1\" class=\"text_area is_empty\" cols=\"40\" rows=\"7\" id=\"avia_4_1\" ><\/textarea><\/p><p class=\"hidden\"><input type=\"text\" name=\"avia_5_1\" class=\"hidden \" id=\"avia_5_1\" value=\"\" \/><\/p><p class='   form_element form_fullwidth av-last-visible-form-element' id='element_avia_6_1'><span class='value_verifier_label'>3 + 5 = ?<\/span><input name=\"avia_6_1_verifier\" type=\"hidden\" id=\"avia_6_1_verifier\" value=\"143482144\"\/><label for=\"avia_6_1\">Para mayor seguridad, responde la siguiente pregunta <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label><input name=\"avia_6_1\" class=\"text_input captcha\" type=\"text\" id=\"avia_6_1\" value=\"\"\/><\/p><p class=' av_form_privacy_check av_contact_privacy_check first_form  form_element form_fullwidth' id='element_avia_7_1'><input  name=\"avia_7_1\" class=\"input_checkbox is_empty\" type=\"checkbox\" id=\"avia_7_1\" value=\"true\"\/><label class=\"input_checkbox_label\" for=\"avia_7_1\">He le\u00eddo y acepto la <a href='https:\/\/comanai.com\/es\/politica-de-privacidad\/' target='_blank'>Pol\u00edtica de privacidad<\/a>  <abbr class=\"required\" title=\"requerido\">*<\/abbr><\/label><\/p><p class=\"form_element \"><input type=\"hidden\" value=\"1\" name=\"avia_generated_form1\" \/><input type=\"submit\" value=\"Enviar\" class=\"button\"  data-sending-label=\"Enviando\"\/><\/p><\/fieldset><\/form><div id=\"ajaxresponse_1\" class=\"ajaxresponse ajaxresponse_1 hidden\"><\/div><\/p>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3xbbao-86925a3c73c739e5a5d03c008c28996d\">\n.flex_cell.av-3xbbao-86925a3c73c739e5a5d03c008c28996d{\nvertical-align:top;\n}\n.responsive #top #wrap_all .flex_cell.av-3xbbao-86925a3c73c739e5a5d03c008c28996d{\npadding:30px 30px 30px 30px !important;\n}\n<\/style>\n<div class='flex_cell av-3xbbao-86925a3c73c739e5a5d03c008c28996d av-gridrow-cell av_one_fifth no_margin  avia-builder-el-33  el_after_av_cell_three_fifth  avia-builder-el-last ' ><div class='flex_cell_inner'><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3602,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3712","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMANAI-STEAM - COMANAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMANAI-STEAM - COMANAI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/\" \/>\n<meta property=\"og:site_name\" content=\"COMANAI\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-07T16:29:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ComanaiGLC\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/comanai-steam\\\/\",\"url\":\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/comanai-steam\\\/\",\"name\":\"COMANAI-STEAM - COMANAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comanai.com\\\/es\\\/#website\"},\"datePublished\":\"2020-03-09T11:11:09+00:00\",\"dateModified\":\"2020-05-07T16:29:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/comanai-steam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/comanai-steam\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/comanai-steam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/comanai.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa\",\"item\":\"https:\\\/\\\/comanai.com\\\/es\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COMANAI-STEAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comanai.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/comanai.com\\\/es\\\/\",\"name\":\"COMANAI\",\"description\":\"LASER-LOGISTICS-ENGINEERING\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comanai.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMANAI-STEAM - COMANAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/","og_locale":"es_ES","og_type":"article","og_title":"COMANAI-STEAM - COMANAI","og_url":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/","og_site_name":"COMANAI","article_modified_time":"2020-05-07T16:29:24+00:00","twitter_card":"summary_large_image","twitter_site":"@ComanaiGLC","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/","url":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/","name":"COMANAI-STEAM - COMANAI","isPartOf":{"@id":"https:\/\/comanai.com\/es\/#website"},"datePublished":"2020-03-09T11:11:09+00:00","dateModified":"2020-05-07T16:29:24+00:00","breadcrumb":{"@id":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comanai.com\/es\/empresa\/comanai-steam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comanai.com\/es\/empresa\/comanai-steam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/comanai.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empresa","item":"https:\/\/comanai.com\/es\/empresa\/"},{"@type":"ListItem","position":3,"name":"COMANAI-STEAM"}]},{"@type":"WebSite","@id":"https:\/\/comanai.com\/es\/#website","url":"https:\/\/comanai.com\/es\/","name":"COMANAI","description":"LASER-LOGISTICS-ENGINEERING","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comanai.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/pages\/3712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/comments?post=3712"}],"version-history":[{"count":62,"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/pages\/3712\/revisions"}],"predecessor-version":[{"id":5163,"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/pages\/3712\/revisions\/5163"}],"up":[{"embeddable":true,"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/pages\/3602"}],"wp:attachment":[{"href":"https:\/\/comanai.com\/es\/wp-json\/wp\/v2\/media?parent=3712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}